{"id":8738,"date":"2019-02-06T16:27:16","date_gmt":"2019-02-06T09:27:16","guid":{"rendered":"https:\/\/www.koh-chang-villa.com\/die-insel-koh-chang\/"},"modified":"2023-10-05T16:42:14","modified_gmt":"2023-10-05T09:42:14","slug":"die-insel-koh-chang","status":"publish","type":"page","link":"https:\/\/koh-chang-villa.com\/de\/die-insel-koh-chang\/","title":{"rendered":"Die Insel Koh Chang"},"content":{"rendered":"<section class=\"l-section wpb_row height_auto width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t\t<!-- START KohChangIsland REVOLUTION SLIDER 6.7.35 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_4_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:#FFFFFF;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_4_1\" class=\" rs-ov-hidden\" style=\"\" data-version=\"6.7.35\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-26\" data-title=\"Slide\" data-thumb=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/welcome-to-koh-chang-sign-crop-150x150.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/koh-chang-villa.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"Die Insel Koh Chang\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/welcome-to-koh-chang-sign-crop.jpg\" data-parallax=\"off\" data-panzoom=\"d:5000;ss:100;se:110;oe:0\/30;\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-43\" data-title=\"Slide\" data-thumb=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/koh-cahng-overview-siam-royal-view-150x150.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/koh-chang-villa.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"Die Insel Koh Chang\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/koh-cahng-overview-siam-royal-view.jpg\" data-parallax=\"off\" data-panzoom=\"d:5000;ss:100;se:110;oe:0\/30;\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-37\" data-title=\"Slide\" data-thumb=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/small-island-near-koh-chang-island-150x150.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/koh-chang-villa.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"Die Insel Koh Chang\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/small-island-near-koh-chang-island.jpg\" data-parallax=\"off\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-44\" data-title=\"Slide\" data-thumb=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Koh-Chang-Island-01-150x150.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/koh-chang-villa.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"Die Insel Koh Chang\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Koh-Chang-Island-01.jpg\" data-parallax=\"off\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-40\" data-title=\"Slide\" data-thumb=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/sunrise-koh-chang-island-150x150.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/koh-chang-villa.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"Die Insel Koh Chang\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/sunrise-koh-chang-island.jpg\" data-parallax=\"off\" data-panzoom=\"d:5000;ss:100;se:120;\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-34\" data-title=\"Slide\" data-thumb=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/pristine-beach-koh-chang-island-thailand-150x150.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/koh-chang-villa.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"Die Insel Koh Chang\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/pristine-beach-koh-chang-island-thailand.jpg\" data-parallax=\"off\" data-panzoom=\"d:5000;ss:100;se:110;\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-35\" data-title=\"Slide\" data-thumb=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/pristine-sand-beach-koh-chang-island-thailand-150x150.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/koh-chang-villa.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"Die Insel Koh Chang\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/pristine-sand-beach-koh-chang-island-thailand.jpg\" data-parallax=\"off\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-28\" data-title=\"Slide\" data-thumb=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Beach-view-koh-chang-villa-1-150x150.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/koh-chang-villa.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"Die Insel Koh Chang\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Beach-view-koh-chang-villa-1.jpg\" data-bg=\"p:left bottom;\" data-parallax=\"off\" data-panzoom=\"d:5000;ss:100;se:110;oe:0\/30;\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-30\" data-title=\"Slide\" data-thumb=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/boat-pier-lighthouse-koh-chang-island-150x150.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/koh-chang-villa.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"Die Insel Koh Chang\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/boat-pier-lighthouse-koh-chang-island.jpg\" data-parallax=\"off\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-32\" data-title=\"Slide\" data-thumb=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/floating-houses-koh-chang-villa-150x150.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/koh-chang-villa.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"Die Insel Koh Chang\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/floating-houses-koh-chang-villa.jpg\" data-parallax=\"off\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-33\" data-title=\"Slide\" data-thumb=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/floating-village-koh-chang-island-150x150.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/koh-chang-villa.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"Die Insel Koh Chang\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/floating-village-koh-chang-island.jpg\" data-parallax=\"off\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-31\" data-title=\"Slide\" data-thumb=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/chinese-shrine-koh-chang-island-150x150.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/koh-chang-villa.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"Die Insel Koh Chang\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/chinese-shrine-koh-chang-island.jpg\" data-bg=\"p:left bottom;\" data-parallax=\"off\" data-panzoom=\"d:5000;ss:100;se:110;os:0\/5;oe:0\/35;\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-29\" data-title=\"Slide\" data-thumb=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/beach-walk-sunset-koh-chang-island-150x150.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/koh-chang-villa.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"Die Insel Koh Chang\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/beach-walk-sunset-koh-chang-island.jpg\" data-bg=\"p:left bottom;\" data-parallax=\"off\" data-panzoom=\"d:5000;ss:100;se:110;oe:0\/20;\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-39\" data-title=\"Slide\" data-thumb=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/stunning-sunset-view-from-koh-chang-villa-150x150.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/koh-chang-villa.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"Die Insel Koh Chang\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/stunning-sunset-view-from-koh-chang-villa.jpg\" data-bg=\"p:left bottom;\" data-parallax=\"off\" data-panzoom=\"d:5000;ss:100;se:120;os:0\/10;oe:-40\/30;\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-42\" data-title=\"Slide\" data-thumb=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Sunset-View-Koh-Chang-Villa-150x150.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/koh-chang-villa.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"Die Insel Koh Chang\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Sunset-View-Koh-Chang-Villa.jpg\" data-bg=\"p:left bottom;\" data-parallax=\"off\" data-panzoom=\"d:5000;ss:100;se:110;oe:0\/10;\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-41\" data-title=\"Slide\" data-thumb=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/sunset-on-koh-chang-island-thailand-150x150.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/koh-chang-villa.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"Die Insel Koh Chang\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/sunset-on-koh-chang-island-thailand.jpg\" data-parallax=\"off\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-36\" data-title=\"Slide\" data-thumb=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/red-sunset-koh-chang-island-150x150.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/koh-chang-villa.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"Die Insel Koh Chang\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/red-sunset-koh-chang-island.jpg\" data-parallax=\"off\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-21\" data-title=\"Slide\" data-thumb=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Sunset-View-Koh-Chang-Villa-2-lr-150x150.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/koh-chang-villa.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"Die Insel Koh Chang\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Sunset-View-Koh-Chang-Villa-2-lr.jpg\" data-parallax=\"off\" data-panzoom=\"d:8000;ss:100;se:120;oe:-40\/20;\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-27\" data-title=\"Slide\" data-thumb=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/amazing-sunset-koh-chang-island-150x150.jpg\" data-anim=\"adpr:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/koh-chang-villa.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"Die Insel Koh Chang\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/amazing-sunset-koh-chang-island.jpg\" data-parallax=\"off\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_4_1',rl:[1240,1024,1024,480],el:[],gw:[1200,1200,1200,600],gh:[620,630,630,450],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider41\"]!==undefined) {window.RS_MODULES.modules[\"revslider41\"].once = false;window.revapi4 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n<\/div><\/div><\/div><\/div><\/div><\/section><!-- Row Backgrounds --><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-8 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h1>Die Insel Koh Chang Thailand<\/h1>\n<p>Koh Chang liegt im Golf von Thailand, nur ein Sprung von Bangkok entfernt und ist eines der bestgeh\u00fctetsten Geheimnisse von Insidern. Eine Insel voller sch\u00f6ner Str\u00e4nde, erstklassiger Hotels mit guter Thaik\u00fcche..<br \/>\nKoh Chang ist ein Paradies, umgeben von smaragd farbenem Wasser und gek\u00fcsst von erstaunlichen Sonnenunterg\u00e4ngen.<\/p>\n<p>Koh Chang ist die gr\u00f6sste Insel im Koh Chang Marine Nationalpark und selbst vielen Thais unbekannt. Die zweitgr\u00f6sste Insel Thailands nach Phuket. Die Inselverwaltung legt grossen Wert auf die Bewahrung der nat\u00fcrlichen Sch\u00f6nheit der Umgebung. Die Inselbesucher sch\u00e4tzen die Sch\u00f6nheit der Natur und die Naturbelassenheit der Insel sehr.<\/p>\n<p>Koh Chang ist ein ruhiges Paradies geblieben, saubere Str\u00e4nde, eingerahmt von Kokospalmen und klares blaues Wasser. Die Entwicklung als Touristendestination geht nat\u00fcrlich auch hier voran, h\u00e4lt sich aber sehr in Grenzen durch die strickte Einhaltung der Bauvorschriften. Koh Chang`s Status als UNESCO World Heritage hat verhindert, dass die Kommerzialisierung der Insel \u00fcberhand nimmt.<\/p>\n<p>Die perfekten weissen Sandstr\u00e4nde, erstaunliche Bergk\u00e4mme, tiefblaues Wasser, sind eine perfekte Umgebung f\u00fcr ruhige Urlaube wie auch f\u00fcr Aktivferien. In Koh Chang sind viele Wassersportarten zuhause. Im t\u00fcrkisfarbenen Wasser zu tauchen ist ein tolles Erlebnis oder die Insel mit einem Kayak oder Kanu zu entdecken ist ein unvergessliches Abenteuer.<\/p>\n<p>Zu der nat\u00fcrlichen Sch\u00f6nheit der Insel empfiehlt es sich als Kontrast zu den ruhigen Str\u00e4nden, einige der Wasserf\u00e4lle, die leicht zug\u00e4nglich sind zu entdecken oder ein Elefanten trekking mitzumachen in den zentralen Bergen von Koh Chang. Dies ist ein Spass f\u00fcr jedes Alter! F\u00fcr Gourmets bietet Koh Chang 2 Kochschulen, wo die thail\u00e4ndische Kochkunst f\u00fcr Anf\u00e4nger, wie auch f\u00fcr Fortgeschrittene erlernt werden kann.<\/p>\n<p>Zur Insel gelangt man mit der F\u00e4hre nach kurzer Fahrzeit von Trat`s Festland aus. In Trat befindet sich auch der Flughafen. Die Tatsache, dass die Insel nur mit dem Schiff erreicht werden kann gibt einem das Gef\u00fchl von Exklusivit\u00e4t und Privatsph\u00e4re und l\u00e4sst die Besucher die Str\u00e4nde im Paradies noch mehr geniessen. Zugang zu Thailand ist \u00fcber den Bangkoker Suvarnabhumi Airport, der die restliche Welt mit Thailand verbindet.<\/p>\n<\/div><\/div><div class=\"w-tabs layout_hor style_trendy switch_click has_scrolling\" style=\"--sections-title-size:1em\"><div class=\"w-tabs-list items_5 align_none\"><div class=\"w-tabs-list-h\"><button class=\"w-tabs-item active\" aria-controls=\"content-wb47\" aria-expanded=\"false\"><span class=\"w-tabs-item-title\">Ausfl\u00fcge<\/span><\/button><button class=\"w-tabs-item\" aria-controls=\"content-vc48\" aria-expanded=\"false\"><span class=\"w-tabs-item-title\">Sport &amp; Aktivit\u00e4ten<\/span><\/button><button class=\"w-tabs-item\" aria-controls=\"content-bd29\" aria-expanded=\"false\"><span class=\"w-tabs-item-title\">Essen &amp; Einkaufen<\/span><\/button><button class=\"w-tabs-item\" aria-controls=\"content-ge29\" aria-expanded=\"false\"><span class=\"w-tabs-item-title\">Gesundheit<\/span><\/button><button class=\"w-tabs-item\" aria-controls=\"content-bf02\" aria-expanded=\"false\"><span class=\"w-tabs-item-title\">Wie kommt man nach Koh Chang?<\/span><\/button><\/div><\/div><div class=\"w-tabs-sections titles-align_none icon_chevron cpos_right\"><div class=\"w-tabs-section active\" id=\"wb47\"><button class=\"w-tabs-section-header active\" aria-controls=\"content-wb47\" aria-expanded=\"true\"><div class=\"w-tabs-section-title\">Ausfl\u00fcge<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-wb47\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>W\u00e4hrend Koh Chang stolz auf seine sch\u00f6nen Str\u00e4nde ist, die spektakul\u00e4re K\u00fcste und die atemberaubenden Sonnenunterg\u00e4nge, gibt es f\u00fcr Menschen die eine Pause von der Erholung, vom Schwimmen und Sonnenbaden m\u00f6chten viel zu tun. Auf der Insel sind einige von Thailands sch\u00f6nsten Wasserf\u00e4lle zuhause. Auch ist Koh Chang das Zentrum vom Mu Koh Chang National Marine Park, einem UNESCO World Heritage Ort.<\/p>\n<h3>Koh Chang&#8217;s Marine Nationalpark<\/h3>\n<p>Eines von Thailands meist geh\u00fcteten Geheimnissen und erstaunliches Naturkunstwerk, der Marine Nationalpark mit seiner unglaublichen Topografie. Unber\u00fchrte Str\u00e4nde, unber\u00fchrte Regenw\u00e4lder, hohe Berge, die die Wasserf\u00e4lle speisen, die wunderbare Unterwasserwelt, alles finden Sie hier auf Koh Chang. Weg von der K\u00fcste, k\u00f6nnen die Besucher sich am warmen Smaragdfarbenen Wasser und den bunten Korallenriffen erfreuen.<\/p>\n<h3>Wasserf\u00e4lle<\/h3>\n<p>Koh Chang`s Zentrum ist die Heimat von einigen der sch\u00f6nsten Wasserf\u00e4lle, wof\u00fcr Thailand bekannt ist. Eine kurze Fahrt mit dem Songthaew (Bathtaxi) bringt die Besucher zu Klong Plu, dem beliebtesten Wasserfall der Insel und dem einzigen an der Westk\u00fcste. Auf der Ostseite findet man den Klong Nonsi und den Klong Nueng Wasserfall, dem athemberaubensten von allen. In Kongoi, k\u00f6nnen Besucher 5 Wasserf\u00e4lle zum Preis von einem besichtigen. Ein anders Beispiel f\u00fcr Natursch\u00f6nheiten ist der Wasserfallpark von Namtok Khlong Phlu, der \u00fcber 3 Stufen von \u00fcber 200 Fuss h\u00f6he f\u00e4llt. Wanderschuhe sind Pflicht f\u00fcr die Besteigung der Treppen auf der Seite aller Wasserf\u00e4lle, und vergessen Sie ihre Kamera nicht!!<\/p>\n<h3>Koh Kood<\/h3>\n<p>Eine der Inseln im S\u00fcden von Koh Chang ist Koh Kood, Sie ist nur ein kurzer Bootstrip entfernt und das Zuhause von von einigen perfekten Sandstr\u00e4nden, kristallklarem Wasser und grossartiges Schnorchel und Tauchrevier. Das weitgehend unerforschte grosse Riff im Norden bietet unversch\u00e4mte Korallensch\u00f6nheiten, w\u00e4hrend der Jungel im S\u00fcden dutzende von Kokosnuss und Gummibaumplantagen beherbergt.<\/p>\n<h3>Koh Maak<\/h3>\n<p>Ganz anders als das gebirgige und mit Urwald bedeckte Koh Chang und Koh Kood, ist Koh Mak eine h\u00fcbsche Insel mit mehr Kokosnuss und Gummibaum Plantagen.<br \/>\nDie fl\u00e4chere Landschaft macht die K\u00fcstenlinie zug\u00e4nglicher und von den Resorts im Westen der Insel aus kann man sehr sch\u00f6n windsurfen. Wie auf Koh Chang, sind auch hier die Str\u00e4nde erstklassig.<\/p>\n<h3>Koh Wai<\/h3>\n<p>Koh Wai ist eine winzige Insel mit zwei malerischen Str\u00e4nden und l\u00e4dt mit seinen Korallenriffen zum Schnorcheln und Tauchen ein. Von vielen wird sie als die sch\u00f6nste Insel der Koh Chang-Kette bezeichnet. W\u00e4hrend die Insel von viele Tagesausfl\u00fcgler besucht wird, ist eine \u00dcbernachtung zu empfehlen um die Ruhe und Sch\u00f6nheit der Insel kennen zulernen.<\/p>\n<h3>Das Dorf Baal Dan Kano<\/h3>\n<p>Das ist ein kleines Dorf mit Koh Chang Ureinwohnern, die den blau gepunkteten Sea Bass aus den umliegenden Gew\u00e4ssern fischen. Das Dorf ist eines der autentischsten in Koh Chang und als Besucher kann man hier die Einheimischen mit ihren Fischen beobachten und den fangfrischen Tagesfang in diversen Restaurants geniessen. Ein &#8220;Must&#8221; f\u00fcr Seafood Liebhaber.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"vc48\"><button class=\"w-tabs-section-header\" aria-controls=\"content-vc48\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Sport &amp; Aktivit\u00e4ten<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-vc48\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Die erstaunlichen Gew\u00e4sser vom Thail\u00e4ndischen Golf und Koh Changs unber\u00fchrte Regenw\u00e4lder machen die Insel zu einem Eldorado f\u00fcr Liebhaber des Outdoor Sports.<br \/>\nHighlights sind tauchen, schnorcheln, segeln, und windsurfen aber man kann auch klettern, wandern und Gourmets k\u00f6nnen die Basics der Thail\u00e4ndischen K\u00fcche in Kochkursen erlernen.<\/p>\n<h3>Tauchen<\/h3>\n<p>Die Gew\u00e4sser rund um Koh Chang sind von den sch\u00f6nsten und attraktivsten in ganz Thailand. Ausserhalb des S\u00fcdwestens der Insel befinden sich mehrere Korallen Riffe und Tiefsee Tauchpl\u00e4tze. Es gibt gen\u00fcgend Anbieter von Tauchausfl\u00fcgen und Tauchkursen auch mit anerkannten Abschl\u00fcssen wie PADI auf der Insel. Die beste Zeit zum Tauchen ist die K\u00fchle Jahreszeit, von Oktober, bis April.<\/p>\n<div data-gyg-href=\"https:\/\/widget.getyourguide.com\/default\/activities.frame\" data-gyg-location-id=\"2677\" data-gyg-locale-code=\"de-CH\" data-gyg-widget=\"activities\" data-gyg-number-of-items=\"7\" data-gyg-excluded-tour-ids=\"257362,454698,465659,465528,442462,454694,398298,223965,514793\" data-gyg-partner-id=\"QLHV0D2\"><\/div>\n<h3>Golf<\/h3>\n<p>Koh Chang hat als kleine Insel keinen eigenen 18 Loch Golfplatz zu bieten. Siam Royal Bay bietet den einzigen Golfplatz auf der Insel an. Es ist allerdings &#8220;nur&#8221; ein 9 Loch Pitch und Put Golfplatz. Man kann zwar sein Handicap hier nicht verbessern, aber es ist trotzdem ein grosser Spass hier zu spielen.<\/p>\n<h3>Kanu<\/h3>\n<p>Das warme Wasser im thail\u00e4ndischen Golf und die h\u00fcbschen Inseln und die Lagunen bieten ein Paradies f\u00fcr Kanu und Kajaking. Siam Royal Bay bietet 2 Verleihstationen f\u00fcr die G\u00e4ste. Entdecken Sie die Insel und ihre Umgebung auf eine andere Art!<\/p>\n<h3>Segeln \/ Yachtsport<\/h3>\n<p>Die Gew\u00e4sser rund um Koh Chang bieten einige tolle Segelm\u00f6glichkeiten. Die stabilen Windverh\u00e4ltnisse zwischen November und M\u00e4rz laden zu Segelt\u00f6rns im Westen der Insel ein. F\u00fcr weniger erfahrene Seeleute empfehlen wir ein Boot mit Skipper zu chartern um die Inseln und den Nationalpark kennen zu lernen.<\/p>\n<h3>Thai Kochschulen<\/h3>\n<p>Besucher, die die Thaik\u00fcche sch\u00e4tzen k\u00f6nnen die Basics in einer von Koh Changs Thai Kochschulen kennenlernen.<br \/>\nZwei der bekanntesten Kochschulen sind Blue Lagoon in Klong Prao Beach und die von Siam Royal Bay in Klong Son. Hier wird von Profis erkl\u00e4rt, wie man Gew\u00fcrze verwendet und zu wunderbaren Aromen zusammenmischt. Man kann ebenfalls lernen, wie man Fr\u00fcchte und Gem\u00fcse sch\u00f6n zubereitet und schnitzen kann.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"bd29\"><button class=\"w-tabs-section-header\" aria-controls=\"content-bd29\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Essen &amp; Einkaufen<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-bd29\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Hand in Hand mit der Entwicklung von Koh Changs Tourismus sind in den letzten Jahren einige gute Restaurants hier auf der Insel entstanden. Als Insel nahe einer K\u00fcstenregion sind nat\u00fcrlich fantastische pitoreske Seafood Restaurants entlang der K\u00fcste entstanden. Alle servieren auch normales Thai Essen.<\/p>\n<p>Koh Chang bietet den Besuchern eine grosse Selektion an gutem Essen. Von traditionellen Thaicurrys bis zu westlichem Essen aus Schweden, Mexiko und Italien ist hier alles zu haben. Manche der Strandresorts haben ihre eigenen Restaurants in den eigenen Komplexen gebaut. Es empfiehlt sich aber etwas von den Touristenpfaden weg die Geheimtips aufzusuchen!<\/p>\n<p>Genau wie mit den Unterk\u00fcnften in Koh Chang empfiehlt es sich ein Bathtaxi zu nehmen und auch an anderen Str\u00e4nden nach netten Restaurants zu suchen. Sodass man jeden Abend einen neuen Platz entdecken kann.<\/p>\n<p>Klong Prao Beach bietet stille, Kerzenlicht Strand-Restaurants, wo man Abendessen mit Meeresgetier direkt vom Golf geniessen kann. Und das mit feinen Cocktails zu den Ger\u00e4uschen von den kleinen Wellen die mit dem Sand am Strand spielen. F\u00fcr eine etwas andere Erfahrung beheimatet Kai Bae Beach eine Anzahl von Fusions Restaurants, von Thai zu Schwedisch, zu Franz\u00f6sisch plus Koh Changs bestbekannte B\u00e4ckerei, wo man jeden Morgen frisches Brot angeboten bekommt.<\/p>\n<p>F\u00fcr den Shopper bietet Koh Chang typische Touristenl\u00e4den und St\u00e4nde f\u00fcr Souvenirs und handgemachte Sachen. Entlang der Strassen in Kai Bae, Lonley Beach und Bangbao. Viele Besucher kaufen Kleider oder handgemachte Souvenirs oder lassen sich vom Schneider etwas machen. Viel mehr hat Koh Chang nicht zu bieten in Sachen Einkauf.<\/p>\n<p>Wie \u00fcberall in Thailand gibts auch hier fast in jedem Resort einen Schneider. Bei Ankunft im Resort kann man sich vermessen lassen und einige Tage sp\u00e4ter die Ma\u00dfanz\u00fcge zu Schn\u00e4ppchen-preisen abholen oder liefern lassen.<\/p>\n<p>White Sand Beach an Koh Changs Westk\u00fcste beheimatet einige K\u00fcnstlershops, zwei klimatisierte Boutiken, die handgefertigte M\u00f6bel verkaufen und spezielle Silberjuwelier Arbeiten.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"ge29\"><button class=\"w-tabs-section-header\" aria-controls=\"content-ge29\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Gesundheit<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-ge29\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Als eine der gr\u00f6ssten Inseln in Thailand, offeriert Koh Chang exzellente Gesundheits-Optionen.<\/p>\n<p>Es gibt einige staatliche und private Spit\u00e4ler und Kliniken \u00fcber die ganze Insel verstreut. Wir empfehlen zwei au\u00dfergew\u00f6hnliche M\u00f6glichkeiten.<\/p>\n<h3>Bangkok International Koh Chang Klinik<\/h3>\n<p>Die Privatklinik ist 24 Stunden offen und befindet sich am S\u00fcdende von White Sand Beach.<\/p>\n<p>Das Spital ist Teil der Bangkok Hospital Group welche erstklassigen Service bieten. Es gibt diese Spit\u00e4ler in einer ganzen Reihe von St\u00e4dten in Thailand. Die Spit\u00e4ler sind mit allem N\u00f6tigen f\u00fcr eine gute Versorgung ausgestattet, haben sogar eine eigene Notfallabteilung und Krankenwagen.<\/p>\n<p><em>Kontaktdetails:<\/em><br \/>\n14\/16 Moo No. 4 Hat Sai Kaow, Koh Chang, Trat 23170 Thailand<br \/>\nTel: +66 (0) 39 551 555, +66 (0) 39 551 151-2<br \/>\nEmail: ick@bgh.co.th<br \/>\nGPS : 12.092918, 102.277500<\/p>\n<h3>Koh Chang Hospital<\/h3>\n<p>Das Koh Chang Hospital ist das oeffentliche Spital auf der Insel und ist an der Westk\u00fcste in Dan Mai. Einfach zu erreichen von Siam Royal Bay aus. Die Aerzte sprechen alle englisch, das Spital ist sauber und gut gef\u00fchrt, hat allerdings nicht die gleichen Ausr\u00fcstungen wie das private Spital.<\/p>\n<p>Es gibt Ultraschall wie auch R\u00f6ntgen, eine allgemeine Abteilung, eine Zahnklinik und sogar eine Druckkammer im Falle eines Tauchunfalls.<\/p>\n<p>Die Klinik behandelt gerne Ausl\u00e4nder zu sehr erschwinglichen Preisen.<\/p>\n<p>Das Spital verf\u00fcgt \u00fcber eine ganze Flotte von Ambulanz Fahrzeugen die 24 Std. verf\u00fcgbar sind. F\u00fcr normale F\u00e4lle \u00f6ffnet die Klinik am Montag bis am Freitag von 08.30 Uhr bis 15.30 Uhr.<\/p>\n<p><em>Kontaktdetails<\/em><br \/>\nTel: +66 39 586 131<br \/>\n24 H Notfall Nummer: <strong>1669<\/strong><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"bf02\"><button class=\"w-tabs-section-header\" aria-controls=\"content-bf02\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Wie kommt man nach Koh Chang?<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-bf02\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Ein Grund f\u00fcr die Ruhe und den Frieden auf Koh Chang, ist, dass die Insel keinen Flughafen besitzt.<br \/>\nDer Hauptanschlusspunkt zur Insel via F\u00e4hre ist am Nordzipfel der Insel. Vom Festland von Trat fahren regelm\u00e4ssig F\u00e4hren nach Koh Chang.<\/p>\n<p>Der Flughafen befindet sich in Trat, man kann aber auch in ca. 5 Stunden von Bangkok mit dem Taxi oder mit einem Bus nach Koh Chang fahren.<\/p>\n<h3>Flughafen<\/h3>\n<p>Der Flughafen von Trat bietet t\u00e4glich mehrere Fl\u00fcge mit Bangkok Airways von und nach Suvarnabumi International Airport. Die Neuer\u00f6ffnung des Flughafens hat das Erreichen von Koh Chang schon sehr vereinfacht.<\/p>\n<p>Der Flughafen ist sehr klein und famili\u00e4r, verf\u00fcgt aber \u00fcber alle notwendigen Einrichtungen f\u00fcr eine reibungslose Flugabwicklung.<br \/>\nEs gibt auch Duty Free, ATM Automaten und Wechselstuben.<\/p>\n<p>Der Transfer vom Flughafen via F\u00e4hre nach Koh Chang findet mit Minibussen oder Taxis statt, die von Bangkok Airways organisiert sind.<\/p>\n<h3>\u00d6ffentliche Transportmittel<\/h3>\n<p>Einer der guten Sachen in Koh Chang ist der F\u00e4hrverkehr zwischen Trat und der Insel. Es ist schon sch\u00f6n wenn man langsam mit der F\u00e4hre auf der Insel ankommt. Die F\u00e4hre braucht ca. 45 Minuten und dockt dann im Koh Chang Ferry Point am Nordzipfel der Insel an. Die F\u00e4hre f\u00e4hrt etwa jede halbe Stunde von morgens um 0700 Uhr bis Abends um 1900 Uhr. Vom F\u00e4hrhafen zu den diversen Resorts oder Hotels wird man von Bathtaxis transportiert.<br \/>\nDas ist eine abenteuerliche Geschichte, weil die Bergstrassen auf Koh Chang unglaublich steil und kurvig sind&#8230;auch das geh\u00f6rt zum Spass, den man hat, wenn man auf Koh Chang herumreist.<\/p>\n<p>Eine Alternative um nach Trat zu reisen ist der VIP Overnight Coach von Bangkok und auch ein &#8220;Overnight Sleeper Train&#8221; vom Bangkoker Hualamphong Bahnhof aus.<\/p>\n<p>Songthaew sind die Haupttransportm\u00f6glichkeit wenn man auf Koh Chang ankommt oder herumreisen m\u00f6chte und kein eigenes Motorrad gemietet hat.<\/p>\n<p>Bevor sie ins Taxi einsteigen, machen sie auf jeden Fall den Fahrpreis ab!<\/p>\n<p>Um auf der Insel herumzukommen ist es empfehlenswert, einen Scooter oder ein Motorrad zu mieten. Das gibts f\u00fcr wenig Geld in fast jedem Resort! Nat\u00fcrlich auch in Siam Royal Bay! Ein Auto zu mieten nur um die Insel zu besichtigen, macht fast keinen Sinn, da sie in ca. 40 Minuten schon alles abgefahren haben&#8230;<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-separator size_medium\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Bilder Galerie<\/h2>\n<\/div><\/div><div class=\"w-slider style_none fit_scaledown nav_dots count_9\"><div class=\"w-slider-h\"><div class=\"royalSlider\"><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"600\" data-rsh=\"400\" data-rsBigImg=\"https:\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Koh-Chang-Luxury-Villa-Koh-Chang-Impresssions-High-View-Cave.jpg\" href=\"https:\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Koh-Chang-Luxury-Villa-Koh-Chang-Impresssions-High-View-Cave-600x400.jpg\"><span data-alt=\"\"><\/span><\/a><div class=\"rsABlock\" data-fadeEffect=\"false\" data-moveEffect=\"none\"><div class=\"w-slider-item-title\">Koh Chang Impressions<\/div><\/div><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"600\" data-rsh=\"400\" data-rsBigImg=\"https:\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Koh-Chang-Luxury-Villa-Koh-Chang-Impresssions-High-View-Main.jpg\" href=\"https:\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Koh-Chang-Luxury-Villa-Koh-Chang-Impresssions-High-View-Main-600x400.jpg\"><span data-alt=\"\"><\/span><\/a><div class=\"rsABlock\" data-fadeEffect=\"false\" data-moveEffect=\"none\"><div class=\"w-slider-item-title\">Koh Chang Impressions<\/div><\/div><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"600\" data-rsh=\"400\" data-rsBigImg=\"https:\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Koh-Chang-Luxury-Villa-Koh-Chang-Impresssions-High-View.jpg\" href=\"https:\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Koh-Chang-Luxury-Villa-Koh-Chang-Impresssions-High-View-600x400.jpg\"><span data-alt=\"\"><\/span><\/a><div class=\"rsABlock\" data-fadeEffect=\"false\" data-moveEffect=\"none\"><div class=\"w-slider-item-title\">Koh Chang Impressions<\/div><\/div><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"400\" data-rsh=\"400\" data-rsBigImg=\"https:\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Koh-Chang-Luxury-Villa-Koh-Chang-Impresssions-Klong-Plue-Waterfall.jpg\" href=\"https:\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Koh-Chang-Luxury-Villa-Koh-Chang-Impresssions-Klong-Plue-Waterfall-400x400.jpg\"><span data-alt=\"\"><\/span><\/a><div class=\"rsABlock\" data-fadeEffect=\"false\" data-moveEffect=\"none\"><div class=\"w-slider-item-title\">Koh Chang Impressions<\/div><\/div><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"600\" data-rsh=\"400\" data-rsBigImg=\"https:\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/koh-chang-villa-thailand-around-the-island-04.jpg\" href=\"https:\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/koh-chang-villa-thailand-around-the-island-04-600x400.jpg\"><span data-alt=\"\"><\/span><\/a><div class=\"rsABlock\" data-fadeEffect=\"false\" data-moveEffect=\"none\"><div class=\"w-slider-item-title\">Koh Chang Impressions<\/div><\/div><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"600\" data-rsh=\"400\" data-rsBigImg=\"https:\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/koh-chang-villa-thailand-around-the-island-05.jpg\" href=\"https:\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/koh-chang-villa-thailand-around-the-island-05-600x400.jpg\"><span data-alt=\"\"><\/span><\/a><div class=\"rsABlock\" data-fadeEffect=\"false\" data-moveEffect=\"none\"><div class=\"w-slider-item-title\">Koh Chang Impressions<\/div><\/div><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"600\" data-rsh=\"400\" data-rsBigImg=\"https:\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Koh-Chang-Luxury-Villa-Koh-Chang-Impresssions-Waterfall.jpg\" href=\"https:\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Koh-Chang-Luxury-Villa-Koh-Chang-Impresssions-Waterfall-600x400.jpg\"><span data-alt=\"\"><\/span><\/a><div class=\"rsABlock\" data-fadeEffect=\"false\" data-moveEffect=\"none\"><div class=\"w-slider-item-title\">Koh Chang Impressions<\/div><\/div><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"600\" data-rsh=\"400\" data-rsBigImg=\"https:\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/koh-chang-thailand-map.jpg\" href=\"https:\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/koh-chang-thailand-map-600x400.jpg\"><span data-alt=\"\"><\/span><\/a><div class=\"rsABlock\" data-fadeEffect=\"false\" data-moveEffect=\"none\"><div class=\"w-slider-item-title\">Koh Chang Island Map | Siam Royal Village<\/div><\/div><\/div><div class=\"rsContent\"><a class=\"rsImg\" data-rsw=\"393\" data-rsh=\"400\" data-rsBigImg=\"https:\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Koh-Chang-Luxury-Villa-Koh-Chang-Marina-Sunset-Yatch.jpg\" href=\"https:\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Koh-Chang-Luxury-Villa-Koh-Chang-Marina-Sunset-Yatch-393x400.jpg\"><span data-alt=\"\"><\/span><\/a><div class=\"rsABlock\" data-fadeEffect=\"false\" data-moveEffect=\"none\"><div class=\"w-slider-item-title\">Marina @ Siam Royal View Village<\/div><\/div><\/div><\/div><img decoding=\"async\" src=\"https:\/\/koh-chang-villa.com\/wp-content\/uploads\/2018\/09\/Koh-Chang-Luxury-Villa-Koh-Chang-Impresssions-High-View-Cave-600x400.jpg\" width=\"600\" height=\"400\" alt loading=\"lazy\"><\/div><div class=\"w-slider-json\" onclick='return {&quot;autoScaleSlider&quot;:true,&quot;addActiveClass&quot;:true,&quot;loop&quot;:true,&quot;fadeInLoadedSlide&quot;:false,&quot;slidesSpacing&quot;:0,&quot;imageScalePadding&quot;:0,&quot;numImagesToPreload&quot;:2,&quot;arrowsNav&quot;:true,&quot;arrowsNavAutoHide&quot;:false,&quot;transitionType&quot;:&quot;fade&quot;,&quot;transitionSpeed&quot;:250,&quot;block&quot;:{&quot;moveEffect&quot;:&quot;none&quot;,&quot;speed&quot;:300},&quot;thumbs&quot;:{&quot;fitInViewport&quot;:false,&quot;firstMargin&quot;:false,&quot;spacing&quot;:4},&quot;controlNavigation&quot;:&quot;bullets&quot;,&quot;autoplay&quot;:{&quot;enabled&quot;:true,&quot;pauseOnHover&quot;:true,&quot;delay&quot;:10000},&quot;fullscreen&quot;:{&quot;enabled&quot;:true},&quot;autoScaleSliderWidth&quot;:600,&quot;autoScaleSliderHeight&quot;:400}'><\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>Video Impressionen<\/h2>\n<\/div><\/div><div class=\"w-video align_none ratio_16x9 has_iframe\"><div class=\"w-video-h\"><iframe title=\"Youtube video player\" src=\"\/\/www.youtube.com\/embed\/miIzijoyV-4?autoplay=0&controls=1&origin=https:\/\/koh-chang-villa.com\/de\/&loop=0&mute=0\" allowfullscreen=\"1\" loading=\"lazy\"><\/iframe><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Die Insel Koh Chang Thailand Koh Chang liegt im Golf von Thailand, nur ein Sprung von Bangkok entfernt und ist eines der bestgeh\u00fctetsten Geheimnisse von Insidern. Eine Insel voller sch\u00f6ner Str\u00e4nde, erstklassiger Hotels mit guter Thaik\u00fcche.. Koh Chang ist ein Paradies, umgeben von smaragd farbenem Wasser und gek\u00fcsst von erstaunlichen Sonnenunterg\u00e4ngen. Koh Chang ist die...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-8738","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Die Insel Koh Chang \/ Wie komme ich dahin \/ Ausfl\u00fcge \/ Koh Chang F\u00fchrer<\/title>\n<meta name=\"description\" content=\"Die Insel Koh Chang, im Golf von Thailand, nur einen Katzensprung von Bangkok entfernt, ist eines der bestgeh\u00fcteten Tourismusgeheimnisse des Landes. Koh Chang&#039;s makellose Str\u00e4nde verweilen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/koh-chang-villa.com\/de\/die-insel-koh-chang\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Insel Koh Chang \/ Wie komme ich dahin \/ Ausfl\u00fcge \/ Koh Chang F\u00fchrer\" \/>\n<meta property=\"og:description\" content=\"Die Insel Koh Chang, im Golf von Thailand, nur einen Katzensprung von Bangkok entfernt, ist eines der bestgeh\u00fcteten Tourismusgeheimnisse des Landes. Koh Chang&#039;s makellose Str\u00e4nde verweilen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/koh-chang-villa.com\/de\/die-insel-koh-chang\/\" \/>\n<meta property=\"og:site_name\" content=\"Koh Chang Villa | Thailand Vacation Villa Rental |\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/koh.chang.villa\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-05T09:42:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/koh-chang-villa.com\/de\/die-insel-koh-chang\/\",\"url\":\"https:\/\/koh-chang-villa.com\/de\/die-insel-koh-chang\/\",\"name\":\"Die Insel Koh Chang \/ Wie komme ich dahin \/ Ausfl\u00fcge \/ Koh Chang F\u00fchrer\",\"isPartOf\":{\"@id\":\"https:\/\/koh-chang-villa.com\/de\/#website\"},\"datePublished\":\"2019-02-06T09:27:16+00:00\",\"dateModified\":\"2023-10-05T09:42:14+00:00\",\"description\":\"Die Insel Koh Chang, im Golf von Thailand, nur einen Katzensprung von Bangkok entfernt, ist eines der bestgeh\u00fcteten Tourismusgeheimnisse des Landes. Koh Chang's makellose Str\u00e4nde verweilen\",\"breadcrumb\":{\"@id\":\"https:\/\/koh-chang-villa.com\/de\/die-insel-koh-chang\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/koh-chang-villa.com\/de\/die-insel-koh-chang\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/koh-chang-villa.com\/de\/die-insel-koh-chang\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/koh-chang-villa.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Insel Koh Chang\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/koh-chang-villa.com\/de\/#website\",\"url\":\"https:\/\/koh-chang-villa.com\/de\/\",\"name\":\"Koh Chang Villa | Thailand Vacation Villa Rental |\",\"description\":\"Welcome at Koh Chang Island\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/koh-chang-villa.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Insel Koh Chang \/ Wie komme ich dahin \/ Ausfl\u00fcge \/ Koh Chang F\u00fchrer","description":"Die Insel Koh Chang, im Golf von Thailand, nur einen Katzensprung von Bangkok entfernt, ist eines der bestgeh\u00fcteten Tourismusgeheimnisse des Landes. Koh Chang's makellose Str\u00e4nde verweilen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/koh-chang-villa.com\/de\/die-insel-koh-chang\/","og_locale":"de_DE","og_type":"article","og_title":"Die Insel Koh Chang \/ Wie komme ich dahin \/ Ausfl\u00fcge \/ Koh Chang F\u00fchrer","og_description":"Die Insel Koh Chang, im Golf von Thailand, nur einen Katzensprung von Bangkok entfernt, ist eines der bestgeh\u00fcteten Tourismusgeheimnisse des Landes. Koh Chang's makellose Str\u00e4nde verweilen","og_url":"https:\/\/koh-chang-villa.com\/de\/die-insel-koh-chang\/","og_site_name":"Koh Chang Villa | Thailand Vacation Villa Rental |","article_publisher":"https:\/\/www.facebook.com\/koh.chang.villa\/","article_modified_time":"2023-10-05T09:42:14+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/koh-chang-villa.com\/de\/die-insel-koh-chang\/","url":"https:\/\/koh-chang-villa.com\/de\/die-insel-koh-chang\/","name":"Die Insel Koh Chang \/ Wie komme ich dahin \/ Ausfl\u00fcge \/ Koh Chang F\u00fchrer","isPartOf":{"@id":"https:\/\/koh-chang-villa.com\/de\/#website"},"datePublished":"2019-02-06T09:27:16+00:00","dateModified":"2023-10-05T09:42:14+00:00","description":"Die Insel Koh Chang, im Golf von Thailand, nur einen Katzensprung von Bangkok entfernt, ist eines der bestgeh\u00fcteten Tourismusgeheimnisse des Landes. Koh Chang's makellose Str\u00e4nde verweilen","breadcrumb":{"@id":"https:\/\/koh-chang-villa.com\/de\/die-insel-koh-chang\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/koh-chang-villa.com\/de\/die-insel-koh-chang\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/koh-chang-villa.com\/de\/die-insel-koh-chang\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/koh-chang-villa.com\/de\/"},{"@type":"ListItem","position":2,"name":"Die Insel Koh Chang"}]},{"@type":"WebSite","@id":"https:\/\/koh-chang-villa.com\/de\/#website","url":"https:\/\/koh-chang-villa.com\/de\/","name":"Koh Chang Villa | Thailand Vacation Villa Rental |","description":"Welcome at Koh Chang Island","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/koh-chang-villa.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"}]}},"_links":{"self":[{"href":"https:\/\/koh-chang-villa.com\/de\/wp-json\/wp\/v2\/pages\/8738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/koh-chang-villa.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/koh-chang-villa.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/koh-chang-villa.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/koh-chang-villa.com\/de\/wp-json\/wp\/v2\/comments?post=8738"}],"version-history":[{"count":0,"href":"https:\/\/koh-chang-villa.com\/de\/wp-json\/wp\/v2\/pages\/8738\/revisions"}],"wp:attachment":[{"href":"https:\/\/koh-chang-villa.com\/de\/wp-json\/wp\/v2\/media?parent=8738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}